{"id":8147,"date":"2026-01-17T15:36:14","date_gmt":"2026-01-17T15:36:14","guid":{"rendered":"https:\/\/monsieur-prevention.com\/?post_type=portfolios&#038;p=8147"},"modified":"2026-01-17T16:10:53","modified_gmt":"2026-01-17T16:10:53","slug":"eine-kurze-gutenachtgeschichte-guten-abend","status":"publish","type":"portfolios","link":"https:\/\/monsieur-prevention.com\/de\/petite-histoire-du-soir-bonsoir\/","title":{"rendered":"Kleine Abendgeschichte, guten Abend!"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"8147\" class=\"elementor elementor-8147\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d058fe3 e-flex e-con-boxed no no e-con e-parent\" data-id=\"d058fe3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfe105e elementor-widget-tablet__width-initial elementor-widget elementor-widget-heading\" data-id=\"cfe105e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kleine Abendgeschichte, guten Abend!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1eba538 e-flex e-con-boxed no no e-con e-parent\" data-id=\"1eba538\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-800963c e-con-full e-flex no no e-con e-child\" data-id=\"800963c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1c6dcf elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"c1c6dcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-093bc44 e-flex e-con-boxed no no e-con e-parent\" data-id=\"093bc44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-655eabd e-con-full e-flex no no e-con e-child\" data-id=\"655eabd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37c13c5 elementor-widget elementor-widget-image\" data-id=\"37c13c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg\" class=\"attachment-large size-large wp-image-8160\" alt=\"\" srcset=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg 1024w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-300x300.jpg 300w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-150x150.jpg 150w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-768x768.jpg 768w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-12x12.jpg 12w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-420x420.jpg 420w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-90x90.jpg 90w, https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1-700x700.jpg 700w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7d8a794 e-con-full e-flex no no e-con e-child\" data-id=\"7d8a794\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-047edc1 elementor-widget elementor-widget-text-editor\" data-id=\"047edc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"1851\" data-end=\"1873\">Kaufen Sie dieses Buch<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a48c16 elementor-widget elementor-widget-text-editor\" data-id=\"1a48c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p data-start=\"1874\" data-end=\"2112\">Dieses Buch ist in franz\u00f6sischer Sprache bei Amazon oder direkt auf der Website des Verlags erh\u00e4ltlich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7e3dcd8 e-con-full e-grid no no e-con e-child\" data-id=\"7e3dcd8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f47cdd0 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"f47cdd0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.amazon.fr\/dp\/B075VWFRDJ?tag=amznfr02-21\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-amazon\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M257.2 162.7c-48.7 1.8-169.5 15.5-169.5 117.5 0 109.5 138.3 114 183.5 43.2 6.5 10.2 35.4 37.5 45.3 46.8l56.8-56S341 288.9 341 261.4V114.3C341 89 316.5 32 228.7 32 140.7 32 94 87 94 136.3l73.5 6.8c16.3-49.5 54.2-49.5 54.2-49.5 40.7-.1 35.5 29.8 35.5 69.1zm0 86.8c0 80-84.2 68-84.2 17.2 0-47.2 50.5-56.7 84.2-57.8v40.6zm136 163.5c-7.7 10-70 67-174.5 67S34.2 408.5 9.7 379c-6.8-7.7 1-11.3 5.5-8.3C88.5 415.2 203 488.5 387.7 401c7.5-3.7 13.3 2 5.5 12zm39.8 2.2c-6.5 15.8-16 26.8-21.2 31-5.5 4.5-9.5 2.7-6.5-3.8s19.3-46.5 12.7-55c-6.5-8.3-37-4.3-48-3.2-10.8 1-13 2-14-.3-2.3-5.7 21.7-15.5 37.5-17.5 15.7-1.8 41-.8 46 5.7 3.7 5.1 0 27.1-6.5 43.1z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Bei Amazon kaufen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6be5bed elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"6be5bed\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/bonheur.fr\/boutique\/petite-histoire-du-soir-bonsoir\/\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-book-open\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M542.22 32.05c-54.8 3.11-163.72 14.43-230.96 55.59-4.64 2.84-7.27 7.89-7.27 13.17v363.87c0 11.55 12.63 18.85 23.28 13.49 69.18-34.82 169.23-44.32 218.7-46.92 16.89-.89 30.02-14.43 30.02-30.66V62.75c.01-17.71-15.35-31.74-33.77-30.7zM264.73 87.64C197.5 46.48 88.58 35.17 33.78 32.05 15.36 31.01 0 45.04 0 62.75V400.6c0 16.24 13.13 29.78 30.02 30.66 49.49 2.6 149.59 12.11 218.77 46.95 10.62 5.35 23.21-1.94 23.21-13.46V100.63c0-5.29-2.62-10.14-7.27-12.99z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Beim Verlag kaufen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f7921bf e-con-full e-flex no no e-con e-child\" data-id=\"f7921bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cba3e3 elementor-widget elementor-widget-text-editor\" data-id=\"3cba3e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"1851\" data-end=\"1873\">Projektpr\u00e4sentation<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4600b7 elementor-widget elementor-widget-text-editor\" data-id=\"c4600b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em data-start=\"216\" data-end=\"252\">Eine kurze Gute-Nacht-Geschichte, guten Abend!<\/em> Dieses Kinderbuch bietet 20 kurze, lustige und originelle Geschichten zum Vorlesen vor dem Schlafengehen. Jede Geschichte erz\u00e4hlt von einem liebenswerten Tier \u2013 Salif, dem Geparden, Jo, dem Lama, Emilie, der Henne, Malinka, der Giraffe, Liling, dem Panda, Jalil, dem Kamel und vielen anderen \u2013, das ein allt\u00e4gliches Abenteuer erlebt, stets humorvoll und fantasievoll erz\u00e4hlt.<\/p><p>Das Buch ist als Abendritual konzipiert und richtet sich an Kinder im Alter von 5 bis 12 Jahren. Es l\u00e4dt sie ein, den Tag auf eine freudige, beruhigende und intime Weise ausklingen zu lassen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e63695a elementor-widget elementor-widget-text-editor\" data-id=\"e63695a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"1851\" data-end=\"1873\">\/ Herausforderungen<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-941d238 elementor-widget elementor-widget-text-editor\" data-id=\"941d238\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Die Schlafenszeit ist ein wichtiger Moment f\u00fcr Kinder, der sowohl die Fantasie anregt als auch die Vermittlung von Bezugspunkten erleichtert. <em data-start=\"898\" data-end=\"934\">Eine kurze Gute-Nacht-Geschichte, guten Abend!<\/em> Es begegnet einer doppelten Herausforderung: wirklich unterhaltsame Geschichten zu bieten, die zum Lesen oder Zuh\u00f6ren anregen, und gleichzeitig grundlegende Werte zu vermitteln, ohne zu moralisieren.<\/p><p>In einem Kontext, in dem p\u00e4dagogische Botschaften manchmal als einschr\u00e4nkend wahrgenommen werden k\u00f6nnen, w\u00e4hlt das Buch Humor, \u00dcbertreibung und \u00dcberraschung, um Lebensregeln, Respekt vor anderen, Selbstvertrauen oder Achtsamkeit gegen\u00fcber der Umwelt anzusprechen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f22f598 elementor-widget elementor-widget-text-editor\" data-id=\"f22f598\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h4 data-start=\"1851\" data-end=\"1873\">\/ Ziele<\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e4ed38 elementor-widget elementor-widget-text-editor\" data-id=\"1e4ed38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das Ziel von <em data-start=\"1443\" data-end=\"1479\">Eine kurze Gute-Nacht-Geschichte, guten Abend!<\/em> Ziel ist es, Kindern durch Lachen grundlegende moralische Werte zu vermitteln, indem zug\u00e4ngliche, einpr\u00e4gsame und altersgerechte Geschichten erz\u00e4hlt werden.<\/p><p>Jede Geschichte schlie\u00dft mit einer klaren Moral ab, die Kindern \u2013 und den sie begleitenden Erwachsenen \u2013 erm\u00f6glicht, die Lehren der Geschichte in Worte zu fassen und gemeinsam zu besprechen. Das Buch m\u00f6chte somit die Fantasie anregen, p\u00e4dagogische Werte vermitteln und die Schlafenszeit in eine Zeit gemeinsamen Vergn\u00fcgens, Nachdenkens und liebevoller Weitergabe verwandeln.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a05b58 e-flex e-con-boxed no no e-con e-parent\" data-id=\"3a05b58\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"featured_media":8160,"template":"","portfolios_categories":[267],"class_list":["post-8147","portfolios","type-portfolios","status-publish","has-post-thumbnail","hentry","portfolios_categories-edition"],"acf":{"featured_video":"","choi\u0441e_menu_page":"global_settings","full_width":false,"header_transparent":false,"header_white":false,"menu_align_page":"default","menu_style":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Petite histoire du soir, bonsoir\u00a0! - Monsieur Pr\u00e9vention<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monsieur-prevention.com\/de\/eine-kurze-gutenachtgeschichte-guten-abend\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Petite histoire du soir, bonsoir\u00a0! - Monsieur Pr\u00e9vention\" \/>\n<meta property=\"og:description\" content=\"Petite histoire du soir, bonsoir\u00a0! \/ Achetez ce livre Ce livre est disponible en fran\u00e7ais sur Amazon ou en vente directe sur le site [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monsieur-prevention.com\/de\/eine-kurze-gutenachtgeschichte-guten-abend\/\" \/>\n<meta property=\"og:site_name\" content=\"Monsieur Pr\u00e9vention\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-17T16:10:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/\",\"name\":\"Petite histoire du soir, bonsoir\u00a0! - Monsieur Pr\u00e9vention\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bonsoir-1.jpg\",\"datePublished\":\"2026-01-17T15:36:14+00:00\",\"dateModified\":\"2026-01-17T16:10:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/#primaryimage\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bonsoir-1.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bonsoir-1.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/petite-histoire-du-soir-bonsoir\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/monsieur-prevention.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/monsieur-prevention.com\\\/portfolios\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Petite histoire du soir, bonsoir\u00a0!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/\",\"name\":\"Monsieur Pr\u00e9vention \u2013 S\u00e9bastien Brochot\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"alternateName\":\"Sebastien Brochot\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monsieur-prevention.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\",\"name\":\"S\u00e9bastien Brochot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"S\u00e9bastien Brochot\"},\"logo\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\"},\"description\":\"Je m'appelle S\u00e9bastien Brochot, je suis sp\u00e9cialiste en strat\u00e9gies de pr\u00e9vention des violences.\",\"sameAs\":[\"https:\\\/\\\/sebastienbrochot.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebastien.brochot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sebastienbrochot\\\/\",\"https:\\\/\\\/x.com\\\/SBrochot\",\"https:\\\/\\\/www.youtube.com\\\/@preventoriumfr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine kurze Gute-Nacht-Geschichte, guten Abend! \u2013 Herr Pr\u00e4vention","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monsieur-prevention.com\/de\/eine-kurze-gutenachtgeschichte-guten-abend\/","og_locale":"de_DE","og_type":"article","og_title":"Petite histoire du soir, bonsoir\u00a0! - Monsieur Pr\u00e9vention","og_description":"Petite histoire du soir, bonsoir\u00a0! \/ Achetez ce livre Ce livre est disponible en fran\u00e7ais sur Amazon ou en vente directe sur le site [&hellip;]","og_url":"https:\/\/monsieur-prevention.com\/de\/eine-kurze-gutenachtgeschichte-guten-abend\/","og_site_name":"Monsieur Pr\u00e9vention","article_modified_time":"2026-01-17T16:10:53+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@SBrochot","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/","url":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/","name":"Eine kurze Gute-Nacht-Geschichte, guten Abend! \u2013 Herr Pr\u00e4vention","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/#primaryimage"},"image":{"@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg","datePublished":"2026-01-17T15:36:14+00:00","dateModified":"2026-01-17T16:10:53+00:00","breadcrumb":{"@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/#primaryimage","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/bonsoir-1.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/monsieur-prevention.com\/petite-histoire-du-soir-bonsoir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/monsieur-prevention.com\/"},{"@type":"ListItem","position":2,"name":"Portfolio","item":"https:\/\/monsieur-prevention.com\/portfolios\/"},{"@type":"ListItem","position":3,"name":"Petite histoire du soir, bonsoir\u00a0!"}]},{"@type":"WebSite","@id":"https:\/\/monsieur-prevention.com\/#website","url":"https:\/\/monsieur-prevention.com\/","name":"Monsieur Pr\u00e9vention - S\u00e9bastien Brochot","description":"Konkrete Antworten auf die Herausforderungen der Gewaltpr\u00e4vention","publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"alternateName":"Sebastien Brochot","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monsieur-prevention.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":["Person","Organization"],"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955","name":"S\u00e9bastien Brochot","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","width":1024,"height":1024,"caption":"S\u00e9bastien Brochot"},"logo":{"@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg"},"description":"Mein Name ist S\u00e9bastien Brochot, ich bin Spezialist f\u00fcr Strategien zur Gewaltpr\u00e4vention.","sameAs":["https:\/\/sebastienbrochot.com\/","https:\/\/www.instagram.com\/sebastien.brochot\/","https:\/\/www.linkedin.com\/in\/sebastienbrochot\/","https:\/\/x.com\/SBrochot","https:\/\/www.youtube.com\/@preventoriumfr"]}]}},"_links":{"self":[{"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/portfolios\/8147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/portfolios"}],"about":[{"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/types\/portfolios"}],"version-history":[{"count":8,"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/portfolios\/8147\/revisions"}],"predecessor-version":[{"id":8164,"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/portfolios\/8147\/revisions\/8164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/media\/8160"}],"wp:attachment":[{"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/media?parent=8147"}],"wp:term":[{"taxonomy":"portfolios_categories","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/de\/wp-json\/wp\/v2\/portfolios_categories?post=8147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}