{"id":8339,"date":"2026-01-06T16:55:12","date_gmt":"2026-01-06T16:55:12","guid":{"rendered":"https:\/\/monsieur-prevention.com\/?p=8339"},"modified":"2026-01-18T17:39:26","modified_gmt":"2026-01-18T17:39:26","slug":"abuso-sexual-o-violencia-sexual-la-eleccion-de-las-palabras","status":"publish","type":"post","link":"https:\/\/monsieur-prevention.com\/es\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/","title":{"rendered":"\u00bfAbuso sexual o violencia sexual? La elecci\u00f3n de las palabras"},"content":{"rendered":"<p>Cette vid\u00e9o interroge un point en apparence linguistique, mais en r\u00e9alit\u00e9 profond\u00e9ment politique, juridique et symbolique\u202f: faut-il parler d\u2019\u00ab\u202fabus sexuel\u202f\u00bb ou de \u00ab\u202fviolences sexuelles\u202f\u00bb pour d\u00e9signer les infractions sexuelles\u202f? Derri\u00e8re ce choix de mots se joue notre mani\u00e8re de comprendre les faits, de qualifier leur gravit\u00e9 et, in fine, de les reconna\u00eetre comme des actes inacceptables.<\/p>\n<div class=\"flex flex-col text-sm pt-4 pb-12\">\n<div id=\"mini-chat-content\" class=\"block\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&:has([data-writing-block])>*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:b074663f-847b-46c7-a36b-8dba35efc390-13\" data-testid=\"conversation-turn-28\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"1190f87b-bb60-4643-a442-0bc6feec9b05\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"562\" data-end=\"1297\">La r\u00e9flexion d\u00e9marre par une mise en situation volontairement simple\u202f: que nous \u00e9voque spontan\u00e9ment le mot \u00ab\u202fabus\u202f\u00bb\u202f? Dans le langage courant, il renvoie \u00e0 l\u2019id\u00e9e d\u2019un usage excessif, d\u2019un d\u00e9passement de limites, comme un abus de pouvoir, un abus de droit ou un abus de m\u00e9dicament. Les d\u00e9finitions lexicographiques vont toutes dans ce sens\u202f: il s\u2019agit d\u2019un mauvais usage ou d\u2019un usage excessif de quelque chose sur lequel on aurait, au d\u00e9part, un certain droit. Or, dans le domaine de la sexualit\u00e9, et a fortiori lorsqu\u2019il s\u2019agit d\u2019enfants, cette logique pose probl\u00e8me\u202f: aucun droit d\u2019usage sexuel sur autrui n\u2019existe. D\u00e8s lors, parler d\u2019\u00ab\u202fabus sexuel\u202f\u00bb introduit une ambigu\u00eft\u00e9 qui peut, sans le vouloir, minimiser la nature des actes.<\/p>\n<p data-start=\"1299\" data-end=\"1814\">La vid\u00e9o rappelle ensuite que ce qui est en cause dans ces situations, ce ne sont pas des exc\u00e8s, mais des actes de domination, de contrainte, d\u2019agression. Le droit fran\u00e7ais parle de violences sexuelles et les d\u00e9finit comme des actes sexuels commis avec violence, contrainte, menace ou surprise. Juridiquement, il s\u2019agit d\u2019infractions clairement identifi\u00e9es\u202f: viols, agressions sexuelles, atteintes sexuelles. Ces termes ne d\u00e9crivent pas un mauvais usage, mais des faits p\u00e9nalement r\u00e9pr\u00e9hensibles, toujours ill\u00e9gaux.<\/p>\n<p data-start=\"1816\" data-end=\"2338\">Un \u00e9clairage historique permet de comprendre pourquoi l\u2019expression \u00ab\u202fabus sexuel\u202f\u00bb s\u2019est impos\u00e9e dans le d\u00e9bat public. Elle provient en grande partie d\u2019une traduction litt\u00e9rale de l\u2019anglais \u00ab\u202fsexual abuse\u202f\u00bb, largement utilis\u00e9e \u00e0 partir des ann\u00e9es 1980. Or cette traduction est discutable\u202f: le mot anglais \u00ab\u202fabuse\u202f\u00bb renvoie davantage \u00e0 des mauvais traitements ou \u00e0 des s\u00e9vices qu\u2019\u00e0 un simple exc\u00e8s. Parler d\u2019\u00ab\u202fabus sexuel\u202f\u00bb en fran\u00e7ais constitue donc un anglicisme qui ne rend pas pleinement compte de la r\u00e9alit\u00e9 des faits.<\/p>\n<p data-start=\"2340\" data-end=\"2929\">L\u2019un des points centraux de la vid\u00e9o est le risque de confusion que ce terme entretient. Dire qu\u2019une personne \u00ab\u202fabuse sexuellement\u202f\u00bb d\u2019un enfant peut sugg\u00e9rer, m\u00eame implicitement, l\u2019id\u00e9e d\u2019un usage excessif, alors qu\u2019il s\u2019agit toujours d\u2019un d\u00e9lit ou d\u2019un crime. Cette confusion affaiblit la fronti\u00e8re entre ce qui est l\u00e9gal et ce qui est ill\u00e9gal, entre ce qui rel\u00e8verait d\u2019un exc\u00e8s et ce qui constitue une agression. \u00c0 l\u2019inverse, le terme \u00ab\u202fviolences sexuelles\u202f\u00bb d\u00e9signe clairement la violence subie et met l\u2019accent sur l\u2019impact de l\u2019acte, ind\u00e9pendamment de la qualification p\u00e9nale finale.<\/p>\n<p data-start=\"2931\" data-end=\"3298\">La vid\u00e9o souligne \u00e9galement que la notion de violence d\u00e9passe le seul cadre judiciaire. Une situation peut \u00eatre v\u00e9cue comme une violence sexuelle m\u00eame en l\u2019absence de poursuites ou de condamnation. Reconna\u00eetre cette dimension est essentiel pour prendre en compte l\u2019exp\u00e9rience des personnes victimes et ne pas r\u00e9duire la r\u00e9alit\u00e9 v\u00e9cue \u00e0 la seule existence d\u2019un proc\u00e8s.<\/p>\n<p data-start=\"3300\" data-end=\"3788\">Un retour r\u00e9flexif personnel vient renforcer cette analyse. L\u2019auteur reconna\u00eet avoir lui-m\u00eame utilis\u00e9 par le pass\u00e9 l\u2019expression \u00ab\u202fabus sexuel\u202f\u00bb, notamment dans un ouvrage destin\u00e9 aux enfants, par souci de clart\u00e9 et parce que ce terme est encore tr\u00e8s r\u00e9pandu et per\u00e7u comme moins brutal. Mais cette vid\u00e9o marque un changement de posture\u202f: le choix assum\u00e9 de parler d\u00e9sormais de violences sexuelles r\u00e9pond \u00e0 un objectif p\u00e9dagogique et \u00e9thique, afin de ne pas minimiser la gravit\u00e9 des actes.<\/p>\n<p data-start=\"3790\" data-end=\"4263\" data-is-last-node=\"\" data-is-only-node=\"\">En conclusion, la vid\u00e9o rappelle que les mots ne sont jamais neutres. Nommer juste, c\u2019est affiner notre vigilance collective, clarifier les rep\u00e8res et mieux appliquer les lois. Parler de violences sexuelles plut\u00f4t que d\u2019abus sexuels, c\u2019est reconna\u00eetre pleinement la violence des actes, leur caract\u00e8re inacceptable et la n\u00e9cessit\u00e9 de les pr\u00e9venir. Le langage, loin d\u2019\u00eatre un simple d\u00e9bat s\u00e9mantique, participe directement \u00e0 la compr\u00e9hension et \u00e0 la pr\u00e9vention des violences.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1\"><\/div>\n<\/div>\n<div class=\"pointer-events-none h-px w-px absolute bottom-0\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cette vid\u00e9o interroge un point en apparence linguistique, mais en r\u00e9alit\u00e9 profond\u00e9ment politique, juridique et symbolique\u202f: faut-il parler d\u2019\u00ab\u202fabus sexuel\u202f\u00bb ou de \u00ab\u202fviolences sexuelles\u202f\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8341,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[270,269],"tags":[271,274,273,272],"class_list":["post-8339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","category-victimes-de-violences","tag-abus-sexuel","tag-infractions-sexuelles","tag-language","tag-violences-sexuelles"],"acf":{"choi\u0441e_menu_page":"global_settings","full_width":false,"header_transparent":false,"header_white":false,"menu_align_page":"default","menu_style":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abus sexuel ou violence sexuelle\u00a0? Le choix des mots - Soci\u00e9t\u00e9, Victimes de violences - Monsieur Pr\u00e9vention<\/title>\n<meta name=\"description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monsieur-prevention.com\/es\/abuso-sexual-o-violencia-sexual-la-eleccion-de-las-palabras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots - Soci\u00e9t\u00e9, Victimes de violences - Monsieur Pr\u00e9vention\" \/>\n<meta property=\"og:description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monsieur-prevention.com\/es\/abuso-sexual-o-violencia-sexual-la-eleccion-de-las-palabras\/\" \/>\n<meta property=\"og:site_name\" content=\"Monsieur Pr\u00e9vention\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-06T16:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-18T17:39:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Brochot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:site\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Brochot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Brochot\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"headline\":\"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots\",\"datePublished\":\"2026-01-06T16:55:12+00:00\",\"dateModified\":\"2026-01-18T17:39:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/\"},\"wordCount\":744,\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/maxresdefault.jpg\",\"keywords\":[\"abus sexuel\",\"infractions sexuelles\",\"language\",\"violences sexuelles\"],\"articleSection\":[\"Soci\u00e9t\u00e9\",\"Victimes de violences\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/\",\"name\":\"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots - Soci\u00e9t\u00e9, Victimes de violences - Monsieur Pr\u00e9vention\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/maxresdefault.jpg\",\"datePublished\":\"2026-01-06T16:55:12+00:00\",\"dateModified\":\"2026-01-18T17:39:26+00:00\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#primaryimage\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/maxresdefault.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/maxresdefault.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/monsieur-prevention.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/\",\"name\":\"Monsieur Pr\u00e9vention \u2013 S\u00e9bastien Brochot\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"alternateName\":\"Sebastien Brochot\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monsieur-prevention.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\",\"name\":\"S\u00e9bastien Brochot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"S\u00e9bastien Brochot\"},\"logo\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\"},\"description\":\"Je m'appelle S\u00e9bastien Brochot, je suis sp\u00e9cialiste en strat\u00e9gies de pr\u00e9vention des violences.\",\"sameAs\":[\"https:\\\/\\\/sebastienbrochot.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebastien.brochot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sebastienbrochot\\\/\",\"https:\\\/\\\/x.com\\\/SBrochot\",\"https:\\\/\\\/www.youtube.com\\\/@preventoriumfr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfAbuso sexual o violencia sexual? La elecci\u00f3n de las palabras - Sociedad, V\u00edctimas de violencia - Sr. Prevenci\u00f3n","description":"Respuestas pr\u00e1cticas a los retos de la prevenci\u00f3n de la violencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monsieur-prevention.com\/es\/abuso-sexual-o-violencia-sexual-la-eleccion-de-las-palabras\/","og_locale":"es_ES","og_type":"article","og_title":"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots - Soci\u00e9t\u00e9, Victimes de violences - Monsieur Pr\u00e9vention","og_description":"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences","og_url":"https:\/\/monsieur-prevention.com\/es\/abuso-sexual-o-violencia-sexual-la-eleccion-de-las-palabras\/","og_site_name":"Monsieur Pr\u00e9vention","article_published_time":"2026-01-06T16:55:12+00:00","article_modified_time":"2026-01-18T17:39:26+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg","type":"image\/jpeg"}],"author":"S\u00e9bastien Brochot","twitter_card":"summary_large_image","twitter_creator":"@SBrochot","twitter_site":"@SBrochot","twitter_misc":{"Escrito por":"S\u00e9bastien Brochot","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#article","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/"},"author":{"name":"S\u00e9bastien Brochot","@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"headline":"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots","datePublished":"2026-01-06T16:55:12+00:00","dateModified":"2026-01-18T17:39:26+00:00","mainEntityOfPage":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/"},"wordCount":744,"publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"image":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg","keywords":["abus sexuel","infractions sexuelles","language","violences sexuelles"],"articleSection":["Soci\u00e9t\u00e9","Victimes de violences"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/","url":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/","name":"\u00bfAbuso sexual o violencia sexual? La elecci\u00f3n de las palabras - Sociedad, V\u00edctimas de violencia - Sr. Prevenci\u00f3n","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#primaryimage"},"image":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg","datePublished":"2026-01-06T16:55:12+00:00","dateModified":"2026-01-18T17:39:26+00:00","description":"Respuestas pr\u00e1cticas a los retos de la prevenci\u00f3n de la violencia","breadcrumb":{"@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#primaryimage","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/maxresdefault.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/monsieur-prevention.com\/abus-sexuel-ou-violence-sexuelle-le-choix-des-mots\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/monsieur-prevention.com\/"},{"@type":"ListItem","position":2,"name":"Abus sexuel ou violence sexuelle\u00a0? Le choix des mots"}]},{"@type":"WebSite","@id":"https:\/\/monsieur-prevention.com\/#website","url":"https:\/\/monsieur-prevention.com\/","name":"Sr. Prevenci\u00f3n - S\u00e9bastien Brochot","description":"Respuestas pr\u00e1cticas a los retos de la prevenci\u00f3n de la violencia","publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"alternateName":"Sebastien Brochot","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monsieur-prevention.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Person","Organization"],"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955","name":"S\u00e9bastien Brochot","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","width":1024,"height":1024,"caption":"S\u00e9bastien Brochot"},"logo":{"@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg"},"description":"Me llamo S\u00e9bastien Brochot y estoy especializado en estrategias de prevenci\u00f3n de la violencia.","sameAs":["https:\/\/sebastienbrochot.com\/","https:\/\/www.instagram.com\/sebastien.brochot\/","https:\/\/www.linkedin.com\/in\/sebastienbrochot\/","https:\/\/x.com\/SBrochot","https:\/\/www.youtube.com\/@preventoriumfr"]}]}},"_links":{"self":[{"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/posts\/8339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/comments?post=8339"}],"version-history":[{"count":4,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/posts\/8339\/revisions"}],"predecessor-version":[{"id":8360,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/posts\/8339\/revisions\/8360"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/media\/8341"}],"wp:attachment":[{"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/media?parent=8339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/categories?post=8339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/es\/wp-json\/wp\/v2\/tags?post=8339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}