{"id":8364,"date":"2024-10-09T18:31:37","date_gmt":"2024-10-09T18:31:37","guid":{"rendered":"https:\/\/monsieur-prevention.com\/?p=8364"},"modified":"2026-01-18T18:32:10","modified_gmt":"2026-01-18T18:32:10","slug":"combattere-la-violenza-attraverso-competenze-psicosociali","status":"publish","type":"post","link":"https:\/\/monsieur-prevention.com\/it\/lutter-contre-les-violences-avec-les-competences-psychosociales\/","title":{"rendered":"Combattere la violenza attraverso le competenze psicosociali"},"content":{"rendered":"<div class=\"flex flex-col text-sm pt-4 pb-12\">\n<div id=\"mini-chat-content\" class=\"block\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&:has([data-writing-block])>*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:b074663f-847b-46c7-a36b-8dba35efc390-19\" data-testid=\"conversation-turn-40\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-8 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"dc3457af-91fa-4f7d-9f0c-c4b53acc20e5\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words dark markdown-new-styling\">\n<p data-start=\"96\" data-end=\"457\">Cette vid\u00e9o montre en quoi le d\u00e9veloppement des comp\u00e9tences psychosociales constitue aujourd\u2019hui l\u2019un des leviers les plus efficaces pour pr\u00e9venir les violences et am\u00e9liorer durablement la sant\u00e9 des individus. Loin d\u2019\u00eatre une id\u00e9e r\u00e9cente ou th\u00e9orique, cette approche s\u2019appuie sur pr\u00e8s de quarante ann\u00e9es de recherches en sant\u00e9 publique et en sciences humaines.<\/p>\n<p data-start=\"459\" data-end=\"990\">Les comp\u00e9tences psychosociales correspondent \u00e0 un ensemble limit\u00e9 mais fondamental de capacit\u00e9s, identifi\u00e9es et consolid\u00e9es progressivement par les professionnels de la sant\u00e9. Contrairement \u00e0 ce que l\u2019on pourrait imaginer, il ne s\u2019agit pas d\u2019une multitude de comp\u00e9tences complexes\u202f: seules neuf comp\u00e9tences fondamentales suffisent \u00e0 aider une personne \u00e0 faire face aux exigences et aux d\u00e9fis de la vie quotidienne. Ces comp\u00e9tences sont organis\u00e9es en trois grandes cat\u00e9gories compl\u00e9mentaires\u202f: cognitives, \u00e9motionnelles et sociales.<\/p>\n<p data-start=\"992\" data-end=\"1641\">Les comp\u00e9tences cognitives renvoient d\u2019abord \u00e0 la conscience de soi. Elles impliquent la capacit\u00e9 \u00e0 se conna\u00eetre, \u00e0 identifier ses forces, ses limites, ses valeurs et ses objectifs. Elles incluent \u00e9galement la pens\u00e9e critique, c\u2019est-\u00e0-dire la capacit\u00e9 \u00e0 rep\u00e9rer les biais, les influences et les pressions ext\u00e9rieures, ainsi qu\u2019une auto-\u00e9valuation positive permettant de reconna\u00eetre ses propres qualit\u00e9s. Enfin, elles supposent de savoir prendre soin de soi, de s\u2019\u00e9couter et d\u2019\u00eatre attentif \u00e0 ses besoins. La vid\u00e9o souligne que nombre d\u2019adultes n\u2019ont eux-m\u00eames jamais pleinement d\u00e9velopp\u00e9 ces comp\u00e9tences, ce qui montre l\u2019ampleur de l\u2019enjeu \u00e9ducatif.<\/p>\n<p data-start=\"1643\" data-end=\"2021\">Ces comp\u00e9tences cognitives s\u2019accompagnent de la capacit\u00e9 \u00e0 se ma\u00eetriser\u202f: savoir g\u00e9rer ses \u00e9motions, se fixer des objectifs r\u00e9alistes et prendre des d\u00e9cisions constructives. Faire des choix responsables et r\u00e9soudre les probl\u00e8mes de mani\u00e8re cr\u00e9ative font \u00e9galement partie de ce socle essentiel, indispensable pour \u00e9viter les r\u00e9ponses impulsives ou violentes face aux difficult\u00e9s.<\/p>\n<p data-start=\"2023\" data-end=\"2603\">Les comp\u00e9tences \u00e9motionnelles occupent une place centrale dans la pr\u00e9vention des violences. Il s\u2019agit d\u2019abord de savoir identifier les \u00e9motions fondamentales et d\u2019en comprendre le sens, mais aussi de reconna\u00eetre le stress et d\u2019en analyser les causes. La r\u00e9gulation \u00e9motionnelle constitue une \u00e9tape cl\u00e9\u202f: \u00eatre capable d\u2019exprimer et de g\u00e9rer ses \u00e9motions de mani\u00e8re positive, sans se faire du mal ni nuire aux autres. La gestion du stress, en particulier dans les moments difficiles de la vie, est pr\u00e9sent\u00e9e comme un facteur d\u00e9terminant pour pr\u00e9venir les passages \u00e0 l\u2019acte violents.<\/p>\n<p data-start=\"2605\" data-end=\"3100\">Les comp\u00e9tences sociales compl\u00e8tent cet ensemble. Elles reposent sur une communication constructive, qui suppose \u00e0 la fois l\u2019\u00e9coute, l\u2019empathie et la capacit\u00e9 \u00e0 s\u2019exprimer clairement. Elles incluent \u00e9galement l\u2019aptitude \u00e0 d\u00e9velopper des relations positives, \u00e0 coop\u00e9rer, \u00e0 s\u2019entraider et \u00e0 adopter des attitudes prosociales. Enfin, elles permettent d\u2019affronter les difficult\u00e9s relationnelles en sachant demander de l\u2019aide, d\u00e9fendre ses droits et r\u00e9soudre les conflits sans recourir \u00e0 la violence.<\/p>\n<p data-start=\"3102\" data-end=\"3543\">La vid\u00e9o s\u2019interroge ensuite sur les effets concrets du d\u00e9veloppement de ces comp\u00e9tences. Si la science s\u2019est peu int\u00e9ress\u00e9e au concept subjectif de bonheur, elle a largement \u00e9tudi\u00e9 l\u2019impact des comp\u00e9tences psychosociales sur la sant\u00e9 mentale et physique. Les r\u00e9sultats sont particuli\u00e8rement solides\u202f: diminution de l\u2019anxi\u00e9t\u00e9, du stress et de la d\u00e9pression, baisse des troubles du comportement et am\u00e9lioration globale du bien-\u00eatre psychique.<\/p>\n<p data-start=\"3545\" data-end=\"3921\">Les programmes de d\u00e9veloppement des comp\u00e9tences psychosociales montrent \u00e9galement un effet majeur sur la r\u00e9duction des conduites \u00e0 risque, comme la consommation de substances, mais aussi sur la diminution du recours \u00e0 la violence, du harc\u00e8lement et des comportements sexuels \u00e0 risque. \u00c0 ces b\u00e9n\u00e9fices s\u2019ajoutent des effets positifs sur la r\u00e9ussite scolaire et professionnelle.<\/p>\n<p data-start=\"3923\" data-end=\"4408\">Ces programmes existent d\u00e9j\u00e0 et sont au c\u0153ur de l\u2019\u00e9ducation \u00e0 la vie affective, relationnelle et sexuelle. En France, une strat\u00e9gie nationale lanc\u00e9e en 2022 vise \u00e0 g\u00e9n\u00e9raliser le d\u00e9veloppement des comp\u00e9tences psychosociales pour les enfants et les jeunes de 3 \u00e0 25 ans, en impliquant \u00e0 la fois les professionnels et les parents. L\u2019objectif est de cr\u00e9er, \u00e0 long terme, un environnement \u00e9ducatif continu permettant de r\u00e9duire durablement les violences et d\u2019am\u00e9liorer la sant\u00e9 collective.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cette vid\u00e9o montre en quoi le d\u00e9veloppement des comp\u00e9tences psychosociales constitue aujourd\u2019hui l\u2019un des leviers les plus efficaces pour pr\u00e9venir les violences et am\u00e9liorer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8367,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[278,277],"tags":[291,287,290,288,289],"class_list":["post-8364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-parentalite","category-pedagogie","tag-competences-emotionnelles","tag-competences-psychosociales","tag-education-a-la-vie-affective","tag-prevention-des-violences","tag-sante-mentale"],"acf":{"choi\u0441e_menu_page":"global_settings","full_width":false,"header_transparent":false,"header_white":false,"menu_align_page":"default","menu_style":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lutter contre les violences avec les comp\u00e9tences psychosociales - Parentalit\u00e9, P\u00e9dagogie - Monsieur Pr\u00e9vention<\/title>\n<meta name=\"description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monsieur-prevention.com\/it\/combattere-la-violenza-attraverso-competenze-psicosociali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lutter contre les violences avec les comp\u00e9tences psychosociales - Parentalit\u00e9, P\u00e9dagogie - Monsieur Pr\u00e9vention\" \/>\n<meta property=\"og:description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monsieur-prevention.com\/it\/combattere-la-violenza-attraverso-competenze-psicosociali\/\" \/>\n<meta property=\"og:site_name\" content=\"Monsieur Pr\u00e9vention\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-09T18:31:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-18T18:32:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Brochot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:site\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Brochot\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Brochot\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"headline\":\"Lutter contre les violences avec les comp\u00e9tences psychosociales\",\"datePublished\":\"2024-10-09T18:31:37+00:00\",\"dateModified\":\"2026-01-18T18:32:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/\"},\"wordCount\":733,\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-1.jpg\",\"keywords\":[\"comp\u00e9tences \u00e9motionnelles\",\"comp\u00e9tences psychosociales\",\"\u00e9ducation \u00e0 la vie affective\",\"pr\u00e9vention des violences\",\"sant\u00e9 mentale\"],\"articleSection\":[\"Parentalit\u00e9\",\"P\u00e9dagogie\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/\",\"name\":\"Lutter contre les violences avec les comp\u00e9tences psychosociales - Parentalit\u00e9, P\u00e9dagogie - Monsieur Pr\u00e9vention\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-1.jpg\",\"datePublished\":\"2024-10-09T18:31:37+00:00\",\"dateModified\":\"2026-01-18T18:32:10+00:00\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-1.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/maxresdefault-1.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/lutter-contre-les-violences-avec-les-competences-psychosociales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/monsieur-prevention.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lutter contre les violences avec les comp\u00e9tences psychosociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/\",\"name\":\"Monsieur Pr\u00e9vention \u2013 S\u00e9bastien Brochot\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"alternateName\":\"Sebastien Brochot\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monsieur-prevention.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\",\"name\":\"S\u00e9bastien Brochot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"S\u00e9bastien Brochot\"},\"logo\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\"},\"description\":\"Je m'appelle S\u00e9bastien Brochot, je suis sp\u00e9cialiste en strat\u00e9gies de pr\u00e9vention des violences.\",\"sameAs\":[\"https:\\\/\\\/sebastienbrochot.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebastien.brochot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sebastienbrochot\\\/\",\"https:\\\/\\\/x.com\\\/SBrochot\",\"https:\\\/\\\/www.youtube.com\\\/@preventoriumfr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Combattere la violenza con competenze psicosociali - Genitorialit\u00e0, Educazione - Mr. Prevention","description":"Risposte pratiche alle sfide della prevenzione della violenza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monsieur-prevention.com\/it\/combattere-la-violenza-attraverso-competenze-psicosociali\/","og_locale":"it_IT","og_type":"article","og_title":"Lutter contre les violences avec les comp\u00e9tences psychosociales - Parentalit\u00e9, P\u00e9dagogie - Monsieur Pr\u00e9vention","og_description":"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences","og_url":"https:\/\/monsieur-prevention.com\/it\/combattere-la-violenza-attraverso-competenze-psicosociali\/","og_site_name":"Monsieur Pr\u00e9vention","article_published_time":"2024-10-09T18:31:37+00:00","article_modified_time":"2026-01-18T18:32:10+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg","type":"image\/jpeg"}],"author":"S\u00e9bastien Brochot","twitter_card":"summary_large_image","twitter_creator":"@SBrochot","twitter_site":"@SBrochot","twitter_misc":{"Scritto da":"S\u00e9bastien Brochot","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#article","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/"},"author":{"name":"S\u00e9bastien Brochot","@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"headline":"Lutter contre les violences avec les comp\u00e9tences psychosociales","datePublished":"2024-10-09T18:31:37+00:00","dateModified":"2026-01-18T18:32:10+00:00","mainEntityOfPage":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/"},"wordCount":733,"publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"image":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg","keywords":["comp\u00e9tences \u00e9motionnelles","comp\u00e9tences psychosociales","\u00e9ducation \u00e0 la vie affective","pr\u00e9vention des violences","sant\u00e9 mentale"],"articleSection":["Parentalit\u00e9","P\u00e9dagogie"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/","url":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/","name":"Combattere la violenza con competenze psicosociali - Genitorialit\u00e0, Educazione - Mr. Prevention","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#primaryimage"},"image":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg","datePublished":"2024-10-09T18:31:37+00:00","dateModified":"2026-01-18T18:32:10+00:00","description":"Risposte pratiche alle sfide della prevenzione della violenza","breadcrumb":{"@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#primaryimage","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2024\/10\/maxresdefault-1.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/monsieur-prevention.com\/lutter-contre-les-violences-avec-les-competences-psychosociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/monsieur-prevention.com\/"},{"@type":"ListItem","position":2,"name":"Lutter contre les violences avec les comp\u00e9tences psychosociales"}]},{"@type":"WebSite","@id":"https:\/\/monsieur-prevention.com\/#website","url":"https:\/\/monsieur-prevention.com\/","name":"Signor Prevenzione - S\u00e9bastien Brochot","description":"Risposte pratiche alle sfide della prevenzione della violenza","publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"alternateName":"Sebastien Brochot","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monsieur-prevention.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955","name":"S\u00e9bastien Brochot","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","width":1024,"height":1024,"caption":"S\u00e9bastien Brochot"},"logo":{"@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg"},"description":"Mi chiamo S\u00e9bastien Brochot e sono specializzato in strategie di prevenzione della violenza.","sameAs":["https:\/\/sebastienbrochot.com\/","https:\/\/www.instagram.com\/sebastien.brochot\/","https:\/\/www.linkedin.com\/in\/sebastienbrochot\/","https:\/\/x.com\/SBrochot","https:\/\/www.youtube.com\/@preventoriumfr"]}]}},"_links":{"self":[{"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/posts\/8364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/comments?post=8364"}],"version-history":[{"count":1,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/posts\/8364\/revisions"}],"predecessor-version":[{"id":8365,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/posts\/8364\/revisions\/8365"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/media\/8367"}],"wp:attachment":[{"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/media?parent=8364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/categories?post=8364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/it\/wp-json\/wp\/v2\/tags?post=8364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}