{"id":8420,"date":"2026-01-20T08:06:08","date_gmt":"2026-01-20T08:06:08","guid":{"rendered":"https:\/\/monsieur-prevention.com\/?p=8420"},"modified":"2026-01-18T19:35:31","modified_gmt":"2026-01-18T19:35:31","slug":"%e6%89%80%e6%9c%89%e6%80%a7%e7%8a%af%e7%bd%aa%e8%80%85%e9%83%bd%e6%98%af%e6%80%a7%e6%9a%b4%e5%8a%9b%e7%9a%84%e5%8f%97%e5%ae%b3%e8%80%85%e5%90%97%ef%bc%9f","status":"publish","type":"post","link":"https:\/\/monsieur-prevention.com\/zh\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/","title":{"rendered":"\u662f\u5426\u6240\u6709\u6027\u72af\u7f6a\u8005\u90fd\u66fe\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\uff1f"},"content":{"rendered":"<p data-start=\"73\" data-end=\"361\">\u672c\u89c6\u9891\u63a2\u8ba8\u4e86\u4e00\u4e2a\u666e\u904d\u5b58\u5728\u7684\u8bef\u89e3\uff1a\u5373\u6240\u6709\u6216\u51e0\u4e4e\u6240\u6709\u6027\u66b4\u529b\u7684\u65bd\u66b4\u8005\u672c\u8eab\u5728\u7ae5\u5e74\u65f6\u671f\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u3002\u79d1\u5b66\u6570\u636e\u8868\u660e\uff0c\u8fd9\u79cd\u8bf4\u6cd5\u5728\u5f88\u5927\u7a0b\u5ea6\u4e0a\u662f\u9519\u8bef\u7684\u3002.<\/p>\n<p data-start=\"363\" data-end=\"954\">\u7814\u7a76\uff0c\u5c24\u5176\u662f\u56fd\u9645\u835f\u8403\u5206\u6790\u8868\u660e\uff0c\u7ea6 70 % \u7684\u6027\u66b4\u529b\u5b9e\u65bd\u8005\u5e76\u4e0d\u58f0\u79f0\u81ea\u5df1\u5728\u5b69\u7ae5\u65f6\u671f\u906d\u53d7\u8fc7\u6027\u8650\u5f85\u3002\u968f\u7740\u65f6\u95f4\u7684\u63a8\u79fb\uff0c\u8fd9\u4e00\u6bd4\u4f8b\u4fdd\u6301\u76f8\u5bf9\u7a33\u5b9a\uff0c\u5c3d\u7ba1\u793e\u4f1a\u8868\u8ff0\u53d1\u751f\u4e86\u53d8\u5316\uff0c\u4eba\u4eec\u5bf9\u6027\u66b4\u529b\u7684\u8ba4\u8bc6\u4e5f\u6709\u6240\u63d0\u9ad8\uff0c\u8fd9\u52a0\u5f3a\u4e86\u8fd9\u4e9b\u7ed3\u679c\u7684\u53ef\u9760\u6027\u3002\u5728\u6240\u6709\u88ab\u5b9a\u7f6a\u7684\u7f6a\u72af\u4e2d\uff0c\u7ea6\u6709 35 % \u62a5\u544a\u66fe\u906d\u53d7\u8fc7\u6027\u8650\u5f85\uff0c\u8fd9\u610f\u5473\u7740\u5927\u591a\u6570\u4eba\u6ca1\u6709\u7ecf\u5386\u8fc7\u8fd9\u79cd\u7279\u5b9a\u7c7b\u578b\u7684\u521b\u4f24\u3002.<\/p>\n<p data-start=\"956\" data-end=\"1356\">\u5728\u5bf9\u513f\u7ae5\u5b9e\u65bd\u6027\u66b4\u529b\u7684\u65bd\u66b4\u8005\u4e2d\uff0c\u7ae5\u5e74\u65f6\u671f\u66fe\u662f\u53d7\u5bb3\u8005\u7684\u4eba\u6240\u5360\u6bd4\u4f8b\u8f83\u9ad8\uff0c\u4f46\u4ecd\u7136\u662f\u5c11\u6570\uff1a\u4e00\u822c\u4f30\u8ba1\u5728 30 % \u5230 50 % \u4e4b\u95f4\uff0c\u5177\u4f53\u53d6\u51b3\u4e8e\u7814\u7a76\u3001\u7814\u7a76\u4eba\u7fa4\u548c\u4f7f\u7528\u7684\u65b9\u6cd5\u3002\u8fd9\u4e9b\u6570\u5b57\u6e05\u695a\u5730\u8868\u660e\uff0c\u4ece\u53d7\u5bb3\u8005\u5230\u65bd\u66b4\u8005\u7684\u8f6c\u53d8\u5e76\u4e0d\u662f\u81ea\u52a8\u786e\u5b9a\u7684\u3002.<\/p>\n<p data-start=\"1358\" data-end=\"1772\">\u53e6\u4e00\u65b9\u9762\uff0c\u7814\u7a76\u8868\u660e\uff0c\u8bb8\u591a\u65bd\u66b4\u8005\u5728\u7ae5\u5e74\u65f6\u671f\u906d\u53d7\u8fc7\u5176\u4ed6\u5f62\u5f0f\u7684\u66b4\u529b\uff1a\u8eab\u4f53\u8650\u5f85\u3001\u5fc3\u7406\u8650\u5f85\u3001\u5ffd\u89c6\u6216\u66b4\u529b\u5bb6\u5ead\u73af\u5883\u3002\u8fd9\u4e9b\u7ecf\u5386\u4f1a\u524a\u5f31\u60c5\u611f\u548c\u5173\u7cfb\u7684\u53d1\u5c55\uff0c\u5e76\u6784\u6210\u98ce\u9669\u56e0\u7d20\uff0c\u5c3d\u7ba1\u5b83\u4eec\u4e0d\u4f1a\u81ea\u52a8\u5bfc\u81f4\u6210\u5e74\u540e\u7684\u6027\u66b4\u529b\u3002.<\/p>\n<p data-start=\"1774\" data-end=\"2149\">\u8fd9\u6bb5\u89c6\u9891\u63d0\u9192\u6211\u4eec\u4e00\u4e2a\u91cd\u8981\u7684\u533a\u522b\uff1a\u4e86\u89e3\u98ce\u9669\u56e0\u7d20\u5e76\u4e0d\u7b49\u4e8e\u4e3a\u81ea\u5df1\u7684\u884c\u4e3a\u8fa9\u62a4\u3002\u4ece\u6cd5\u5f8b\u548c\u9053\u5fb7\u89d2\u5ea6\u8bb2\uff0c\u6bcf\u4e2a\u4eba\u90fd\u8981\u5bf9\u81ea\u5df1\u7684\u884c\u4e3a\u8d1f\u5168\u90e8\u8d23\u4efb\u3002\u5145\u6ee1\u66b4\u529b\u7684\u7ae5\u5e74\u5e76\u4e0d\u80fd\u6210\u4e3a\u884c\u4e3a\u7684\u501f\u53e3\uff0c\u4f46\u5b83\u5e94\u8be5\u6210\u4e3a\u4e00\u79cd\u8b66\u793a\uff0c\u63d0\u9192\u4eba\u4eec\u9700\u8981\u53ca\u65e9\u91c7\u53d6\u9002\u5f53\u7684\u9884\u9632\u63aa\u65bd\u3002.<\/p>\n<p data-start=\"2151\" data-end=\"2492\">\u56e0\u6b64\uff0c\u6709\u6548\u9884\u9632\u7684\u57fa\u7840\u662f\u8bc6\u522b\u906d\u53d7\u66b4\u529b\u7684\u513f\u7ae5\u3001\u7167\u987e\u4ed6\u4eec\u3001\u652f\u6301\u5bb6\u5ead\u3001\u57f9\u8bad\u4e13\u4e1a\u4eba\u5458\u548c\u57f9\u517b\u793e\u4f1a\u5fc3\u7406\u6280\u80fd\u3002\u53ea\u6709\u5728\u66b4\u529b\u53d1\u751f\u4e4b\u524d\u53ca\u65e9\u5e72\u9884\uff0c\u6211\u4eec\u624d\u80fd\u957f\u671f\u51cf\u5c11\u6027\u66b4\u529b\u3002.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cette vid\u00e9o s\u2019attaque \u00e0 une id\u00e9e re\u00e7ue tr\u00e8s r\u00e9pandue\u202f: celle selon laquelle tous, ou presque tous, les auteurs de violences sexuelles auraient eux-m\u00eames \u00e9t\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":8470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[275,269],"tags":[380,375,382,381,295,272],"class_list":["post-8420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-auteurs-de-violences","category-victimes-de-violences","tag-agresseurs-sexuels","tag-enfance","tag-facteurs-de-risque","tag-idees-recues","tag-prevention","tag-violences-sexuelles"],"acf":{"choi\u0441e_menu_page":"global_settings","full_width":false,"header_transparent":false,"header_white":false,"menu_align_page":"default","menu_style":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles ? - Auteurs de violences, Victimes de violences - Monsieur Pr\u00e9vention<\/title>\n<meta name=\"description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/monsieur-prevention.com\/zh\/\u6240\u6709\u6027\u72af\u7f6a\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles ? - Auteurs de violences, Victimes de violences - Monsieur Pr\u00e9vention\" \/>\n<meta property=\"og:description\" content=\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\" \/>\n<meta property=\"og:url\" content=\"https:\/\/monsieur-prevention.com\/zh\/\u6240\u6709\u6027\u72af\u7f6a\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\/\" \/>\n<meta property=\"og:site_name\" content=\"Monsieur Pr\u00e9vention\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T08:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Brochot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:site\" content=\"@SBrochot\" \/>\n<meta name=\"twitter:label1\" content=\"\u4f5c\u8005\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9bastien Brochot\" \/>\n\t<meta name=\"twitter:label2\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Brochot\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"headline\":\"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles\u202f?\",\"datePublished\":\"2026-01-20T08:06:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/\"},\"wordCount\":399,\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/auteursvictimes.jpg\",\"keywords\":[\"agresseurs sexuels\",\"enfance\",\"facteurs de risque\",\"id\u00e9es re\u00e7ues\",\"pr\u00e9vention\",\"violences sexuelles\"],\"articleSection\":[\"Auteurs de violences\",\"Victimes de violences\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/\",\"name\":\"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles ? - Auteurs de violences, Victimes de violences - Monsieur Pr\u00e9vention\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/auteursvictimes.jpg\",\"datePublished\":\"2026-01-20T08:06:08+00:00\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/auteursvictimes.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/auteursvictimes.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/monsieur-prevention.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles\u202f?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#website\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/\",\"name\":\"Monsieur Pr\u00e9vention \u2013 S\u00e9bastien Brochot\",\"description\":\"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences\",\"publisher\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\"},\"alternateName\":\"Sebastien Brochot\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/monsieur-prevention.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/#\\\/schema\\\/person\\\/a98adec1ea87e537031f136cbe7ad955\",\"name\":\"S\u00e9bastien Brochot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"url\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"contentUrl\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"S\u00e9bastien Brochot\"},\"logo\":{\"@id\":\"https:\\\/\\\/monsieur-prevention.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/favicon.jpg\"},\"description\":\"Je m'appelle S\u00e9bastien Brochot, je suis sp\u00e9cialiste en strat\u00e9gies de pr\u00e9vention des violences.\",\"sameAs\":[\"https:\\\/\\\/sebastienbrochot.com\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebastien.brochot\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sebastienbrochot\\\/\",\"https:\\\/\\\/x.com\\\/SBrochot\",\"https:\\\/\\\/www.youtube.com\\\/@preventoriumfr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u6240\u6709\u6027\u4fb5\u72af\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\u2014\u2014\u66b4\u529b\u65bd\u5bb3\u8005\uff0c\u66b4\u529b\u53d7\u5bb3\u8005\u2014\u2014\u9884\u9632\u5148\u751f","description":"\u5207\u5b9e\u5e94\u5bf9\u9884\u9632\u66b4\u529b\u7684\u6311\u6218","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/monsieur-prevention.com\/zh\/\u6240\u6709\u6027\u72af\u7f6a\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\/","og_locale":"zh_CN","og_type":"article","og_title":"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles ? - Auteurs de violences, Victimes de violences - Monsieur Pr\u00e9vention","og_description":"Des r\u00e9ponses concr\u00e8tes aux enjeux de la pr\u00e9vention des violences","og_url":"https:\/\/monsieur-prevention.com\/zh\/\u6240\u6709\u6027\u72af\u7f6a\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\/","og_site_name":"Monsieur Pr\u00e9vention","article_published_time":"2026-01-20T08:06:08+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg","type":"image\/jpeg"}],"author":"S\u00e9bastien Brochot","twitter_card":"summary_large_image","twitter_creator":"@SBrochot","twitter_site":"@SBrochot","twitter_misc":{"\u4f5c\u8005":"S\u00e9bastien Brochot","\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"2 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#article","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/"},"author":{"name":"S\u00e9bastien Brochot","@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"headline":"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles\u202f?","datePublished":"2026-01-20T08:06:08+00:00","mainEntityOfPage":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/"},"wordCount":399,"publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"image":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg","keywords":["agresseurs sexuels","enfance","facteurs de risque","id\u00e9es re\u00e7ues","pr\u00e9vention","violences sexuelles"],"articleSection":["Auteurs de violences","Victimes de violences"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/","url":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/","name":"\u6240\u6709\u6027\u4fb5\u72af\u8005\u90fd\u662f\u6027\u66b4\u529b\u7684\u53d7\u5bb3\u8005\u5417\uff1f\u2014\u2014\u66b4\u529b\u65bd\u5bb3\u8005\uff0c\u66b4\u529b\u53d7\u5bb3\u8005\u2014\u2014\u9884\u9632\u5148\u751f","isPartOf":{"@id":"https:\/\/monsieur-prevention.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#primaryimage"},"image":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg","datePublished":"2026-01-20T08:06:08+00:00","description":"\u5207\u5b9e\u5e94\u5bf9\u9884\u9632\u66b4\u529b\u7684\u6311\u6218","breadcrumb":{"@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#primaryimage","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/auteursvictimes.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/monsieur-prevention.com\/tous-les-agresseurs-sexuels-ont-il-ete-victimes-de-violences-sexuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/monsieur-prevention.com\/"},{"@type":"ListItem","position":2,"name":"Tous les agresseurs sexuels ont-il \u00e9t\u00e9 victimes de violences sexuelles\u202f?"}]},{"@type":"WebSite","@id":"https:\/\/monsieur-prevention.com\/#website","url":"https:\/\/monsieur-prevention.com\/","name":"\u9884\u9632\u5148\u751f - \u585e\u5df4\u65af\u8482\u5b89-\u5e03\u7f57\u8096","description":"\u5207\u5b9e\u5e94\u5bf9\u9884\u9632\u66b4\u529b\u7684\u6311\u6218","publisher":{"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955"},"alternateName":"Sebastien Brochot","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/monsieur-prevention.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":["Person","Organization"],"@id":"https:\/\/monsieur-prevention.com\/#\/schema\/person\/a98adec1ea87e537031f136cbe7ad955","name":"\u585e\u5df4\u65af\u8482\u5b89-\u5e03\u7f57\u8096","image":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","url":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","contentUrl":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg","width":1024,"height":1024,"caption":"S\u00e9bastien Brochot"},"logo":{"@id":"https:\/\/monsieur-prevention.com\/wp-content\/uploads\/2026\/01\/favicon.jpg"},"description":"\u6211\u53eb\u585e\u5df4\u65af\u8482\u5b89-\u5e03\u7f57\u8096\uff08S\u00e9bastien Brochot\uff09\uff0c\u4e13\u95e8\u7814\u7a76\u9884\u9632\u66b4\u529b\u6218\u7565\u3002.","sameAs":["https:\/\/sebastienbrochot.com\/","https:\/\/www.instagram.com\/sebastien.brochot\/","https:\/\/www.linkedin.com\/in\/sebastienbrochot\/","https:\/\/x.com\/SBrochot","https:\/\/www.youtube.com\/@preventoriumfr"]}]}},"_links":{"self":[{"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/posts\/8420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/comments?post=8420"}],"version-history":[{"count":1,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/posts\/8420\/revisions"}],"predecessor-version":[{"id":8421,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/posts\/8420\/revisions\/8421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/media\/8470"}],"wp:attachment":[{"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/media?parent=8420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/categories?post=8420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/monsieur-prevention.com\/zh\/wp-json\/wp\/v2\/tags?post=8420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}